{"id":30458,"date":"2026-07-15T11:26:59","date_gmt":"2026-07-15T11:26:59","guid":{"rendered":"https:\/\/las-noticias.com.mx\/index.php\/2026\/07\/15\/vecinos-respaldan-el-cablebus-frente-al-congreso-de-puebla-destacan-beneficios-para-la-zona-norte\/"},"modified":"2026-07-15T17:27:01","modified_gmt":"2026-07-15T17:27:01","slug":"vecinos-respaldan-el-cablebus-frente-al-congreso-de-puebla-destacan-beneficios-para-la-zona-norte","status":"publish","type":"post","link":"https:\/\/las-noticias.com.mx\/index.php\/2026\/07\/15\/vecinos-respaldan-el-cablebus-frente-al-congreso-de-puebla-destacan-beneficios-para-la-zona-norte\/","title":{"rendered":"Vecinos respaldan el Cableb\u00fas frente al Congreso de Puebla; destacan beneficios para la zona norte"},"content":{"rendered":"<p>Durante la comparecencia del coordinador del Gabinete, Jos\u00e9 Luis Garc\u00eda Parra, en el Congreso del Estado, un grupo de vecinos de diversas colonias del municipio de Puebla se manifest\u00f3 a favor de la construcci\u00f3n del Sistema de Transporte por Cable. La protesta tuvo lugar el mi\u00e9rcoles 15 de julio de 2026, coincidiendo con la sesi\u00f3n legislativa.  <\/p>\n<p>Encabezados por Armando M\u00e9ndez, los ciudadanos se\u00f1alaron que el proyecto contribuir\u00e1 a mejorar la movilidad en las zonas perif\u00e9ricas de la ciudad, permitiendo cruzar Puebla en menos tiempo y a un costo accesible, especialmente para quienes habitan en colonias alejadas del centro.  <\/p>\n<p>\u201cPrincipalmente es por el beneficio que trae a las colonias en las periferias de la ciudad\u201d, afirm\u00f3 M\u00e9ndez, quien adem\u00e1s destac\u00f3 que el sistema contempla viajes gratuitos para adultos mayores, estudiantes de educaci\u00f3n b\u00e1sica y personas con discapacidad.  <\/p>\n<p>El vecino subray\u00f3 que el Cableb\u00fas ayudar\u00e1 a reducir el tr\u00e1fico vehicular y asegur\u00f3 que los habitantes del norte de la capital ser\u00e1n de los principales beneficiados. \u201cQuienes vivimos en Amalucan, en la zona norte, vamos a ser beneficiados\u201d, agreg\u00f3.  <\/p>\n<p>Respecto a las cr\u00edticas que ha generado el proyecto, M\u00e9ndez consider\u00f3 que forman parte de cualquier obra de gran magnitud y se\u00f1al\u00f3 que varios de los asistentes han buscado informarse sobre los alcances del sistema.  <\/p>\n<p>Finalmente, expres\u00f3 su confianza en que durante la comparecencia de Jos\u00e9 Luis Garc\u00eda Parra se brinde una explicaci\u00f3n m\u00e1s detallada sobre el proyecto y sus beneficios para la poblaci\u00f3n.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/Diario_Cambio\/status\/2077440739064123640\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante la comparecencia del coordinador del Gabinete, Jos\u00e9 Luis Garc\u00eda Parra, en el Congreso del Estado, un grupo de vecinos de diversas colonias del municipio de Puebla se manifest\u00f3 a favor de la construcci\u00f3n del Sistema de Transporte por Cable. La protesta tuvo lugar el mi\u00e9rcoles 15 de julio de 2026, coincidiendo con la sesi\u00f3n&#8230;<\/p>\n","protected":false},"author":1,"featured_media":30457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-30458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"_links":{"self":[{"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/30458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=30458"}],"version-history":[{"count":1,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/30458\/revisions"}],"predecessor-version":[{"id":30459,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/30458\/revisions\/30459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/30457"}],"wp:attachment":[{"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=30458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=30458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=30458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}