{"id":27402,"date":"2026-05-22T14:49:50","date_gmt":"2026-05-22T14:49:50","guid":{"rendered":"https:\/\/las-noticias.com.mx\/index.php\/2026\/05\/22\/juez-en-salta-argentina-ordena-pension-alimenticia-para-perrito-tras-divorcio-de-una-pareja\/"},"modified":"2026-05-22T14:49:50","modified_gmt":"2026-05-22T14:49:50","slug":"juez-en-salta-argentina-ordena-pension-alimenticia-para-perrito-tras-divorcio-de-una-pareja","status":"publish","type":"post","link":"https:\/\/las-noticias.com.mx\/index.php\/2026\/05\/22\/juez-en-salta-argentina-ordena-pension-alimenticia-para-perrito-tras-divorcio-de-una-pareja\/","title":{"rendered":"Juez en Salta, Argentina, ordena pensi\u00f3n alimenticia para perrito tras divorcio de una pareja"},"content":{"rendered":"<p>Un juez de Salta, Argentina, emiti\u00f3 una resoluci\u00f3n judicial in\u00e9dita al ordenar a un hombre pagar una pensi\u00f3n alimenticia para el perrito que compart\u00eda con su exesposa antes del divorcio. El fallo ha llamado la atenci\u00f3n porque reconoce formalmente a las mascotas como seres sintientes y miembros del n\u00facleo familiar, bajo el concepto de familias multiespecie.<\/p>\n<p>El caso comenz\u00f3 despu\u00e9s de que la mujer asumiera completamente el cuidado del perrito tras la separaci\u00f3n. Ante el aumento de gastos relacionados con alimento, vacunas, medicamentos y atenci\u00f3n veterinaria, decidi\u00f3 acudir a los tribunales para solicitar apoyo econ\u00f3mico, argumentando que la manutenci\u00f3n del animal afectaba su estabilidad financiera.<\/p>\n<p>Tras analizar la situaci\u00f3n, el tribunal concluy\u00f3 que el animal deb\u00eda ser considerado parte de la familia. Con base en ello, estableci\u00f3 que el demandado deber\u00e1 contribuir econ\u00f3micamente para cubrir las necesidades del perro. La resoluci\u00f3n tambi\u00e9n se\u00f1ala que el monto definitivo depender\u00e1 de los gastos de manutenci\u00f3n y atenci\u00f3n m\u00e9dica del can, as\u00ed como de los ingresos econ\u00f3micos del hombre.<\/p>\n<p>Adem\u00e1s de la pensi\u00f3n, el juez orden\u00f3 un r\u00e9gimen de visitas obligatorio para preservar el v\u00ednculo afectivo con la mascota. Las autoridades se\u00f1alaron que ambos integrantes de la expareja tienen responsabilidad sobre el bienestar del animal.<\/p>\n<p>Por otra parte, esta decisi\u00f3n gener\u00f3 debate en redes sociales, pues mientras algunos usuarios celebraron el reconocimiento legal de las mascotas dentro de las familias, otros consideraron excesivo equiparar estos casos con la manutenci\u00f3n de hijos humanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un juez de Salta, Argentina, emiti\u00f3 una resoluci\u00f3n judicial in\u00e9dita al ordenar a un hombre pagar una pensi\u00f3n alimenticia para el perrito que compart\u00eda con su exesposa antes del divorcio. El fallo ha llamado la atenci\u00f3n porque reconoce formalmente a las mascotas como seres sintientes y miembros del n\u00facleo familiar, bajo el concepto de familias&#8230;<\/p>\n","protected":false},"author":1,"featured_media":27401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-27402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/27402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=27402"}],"version-history":[{"count":0,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/27402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/27401"}],"wp:attachment":[{"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=27402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=27402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/las-noticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=27402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}